{"id":12646,"date":"2012-05-23T14:47:41","date_gmt":"2012-05-23T12:47:41","guid":{"rendered":"http:\/\/www.actividades-mcp.es\/gestionresiduos\/?p=12646"},"modified":"2017-07-04T13:29:47","modified_gmt":"2017-07-04T11:29:47","slug":"casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas","status":"publish","type":"post","link":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/","title":{"rendered":"Casas modulares fabricadas con contenedores: baratas y ecol\u00f3gicas"},"content":{"rendered":"<p><!--more-->El uso de contenedores en proyectos de arquitectura sostenible cada vez cuenta con m\u00e1s adeptos, desde el eco arquitecto <a href=\"http:\/\/www.luisdegarrido.com\/contenido.html\" target=\"_blank\" rel=\"noopener\">Luis de Garrido<\/a>, hasta <a href=\"http:\/\/www.infiniski.com\/\" target=\"_blank\" rel=\"noopener\">Infiniski<\/a> o <a href=\"http:\/\/ecotechdesign.com\/\" target=\"_blank\" rel=\"noopener\">Eco tech design<\/a>, entre muchos otros, se han dejado seducir por las cualidades de estos habit\u00e1culos dise\u00f1ados para almacenar y transportar mercanc\u00edas a gran distancia, pero que da la causalidad de que <strong>tienen una escala humana adecuada, es decir, son v\u00e1lidos para proyectar espacios habitables.<a href=\"http:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/casitaaas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12703\" title=\"Distintas casas que pueden hacerse reciclando containers\" src=\"http:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/casitaaas.jpg\" alt=\"\" width=\"708\" height=\"318\" \/><\/a><\/strong><\/p>\n<p><strong>El econ\u00f3mico precio de estos edificios,<\/strong> comparado con la tendencia actual del mercado de la construcci\u00f3n, ha llamado la atenci\u00f3n de muchos pa\u00edses de Latinoam\u00e9rica que quieren promover la edificaci\u00f3n de viviendas de bajo coste para gente con pocos recursos. <strong>Las construcciones son entre un 25 y 30% mas baratas en comparaci\u00f3n con las construcciones tradicionales.<\/strong><\/p>\n<p>Construir una de estas casas <strong>cuesta alrededor de unos tres meses aproxim\u00e1damente. <\/strong>Cuando se realiza una construcci\u00f3n de este tipo bastan unas pocas semanas para finalizar la obra y <strong>los costes se reducen considerablemente<\/strong>. El hecho de trabajar con materiales reciclados no quiere decir que son de menor calidad, por el contrario cumple con todas las garant\u00edas de calidad y su material en s\u00ed, posee caracter\u00edsticas \u00fanicas de resistencia que no tienen otros.<\/p>\n<p><span style=\"color: #888888;\"><span style=\"font-size: medium;\"><strong>R4 House<\/strong><\/span><\/span><\/p>\n<p>R4 House, vivienda bioclim\u00e1tica y sostenible, realizada \u00edntegramente con residuos, autosuficiente en agua y energ\u00eda (consumo energ\u00e9tico cero). <strong>Esta vivienda est\u00e1 considerada como un referente global en arquitectura sostenible<\/strong>. Luis de Garrido, su dise\u00f1ador, fue elegido \u201cArchitect of the year 2008\u201d por la ISBA, en colaboraci\u00f3n con el AIA, por la gran cantidad de aportaciones a la arquitectura sostenible de este proyecto.<\/p>\n<a href=\"http:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/contenedores1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12672\" title=\"Casa de Luis de Garrido de las 4R\" src=\"http:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/contenedores1.jpg\" alt=\"\" width=\"450\" height=\"299\" \/><\/a>\n<p><span style=\"color: #888888;\"><span style=\"font-size: medium;\"><strong>Manifiesto House<\/strong><\/span><\/span><\/p>\n<p>La Manifesto House est\u00e1 ubicada en Chile, y ha sido realizada por el estudio Infinisky. Esta empresa se caracteriza por utilizar un proceso de construcci\u00f3n modular, amigable con el medio ambiente y de est\u00e9tica vanguardista. Sus viviendas, hechas con contenedores reciclados, pallets, madera recuperada y con sistemas de generaci\u00f3n de energ\u00eda a partir de fuentes renovables, <strong>aseguran ser entre un 15 a 20% m\u00e1s baratas que una tradicional y pueden construirse en la mitad del tiempo.<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/Manifesto-House.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12647\" title=\"Manifesto House ubicada en Chile\" src=\"http:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/Manifesto-House.jpg\" alt=\"\" width=\"538\" height=\"396\" \/><\/a><\/p>\n<p><span style=\"color: #888888;\"><span style=\"font-size: medium;\"><strong>Ciudad Container de Londres<\/strong><\/span><\/span><\/p>\n<p>Una peque\u00f1a ciudad de 14.000 metros cuadrados construida con container marinos totalmente independiente para mantener 150 a 200 personas dividida en 2 partes, area de trabajo y zona residencial. Adem\u00e1s de viviendas, los contenedores de barco tambi\u00e9n se emplean en la construcci\u00f3n de oficinas, centros comunitarios, locales de ensayo, colegios y enfermer\u00edas. En total, en Reino Unido hay 36 &#8216;edificios contenedor&#8217;, muchos de ellos <strong>promovidos por entidades p\u00fablicas<\/strong>. Eric Reynolds, es el fundador de la idea,\u00a0\u00a0estas viviendas se hicieron en plan experimento\u00a0como<strong> \u00abuna alternativa al sistema de vivienda tradicional\u00bb.<\/strong><\/p>\n<p><strong><a href=\"http:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/Untitled-12.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12677\" title=\"Algunos de los edificios que podemos encontrar en la ciudad de Londres\" src=\"http:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/Untitled-12.jpg\" alt=\"\" width=\"595\" height=\"223\" \/><\/a><br \/>\n<\/strong><\/p>\n<p><span style=\"color: #888888;\"><span style=\"font-size: medium;\"><strong>Shipping Container House<\/strong><\/span><\/span><\/p>\n<p>Ubicada en alg\u00fan lugar de Colorado, Estados Unidos, la Shipping Container House, <strong>adem\u00e1s de estar fabricada con containers y otros materiales reciclados, es completamente off-grid.<\/strong> Esto quiere decir que tiene la capacidad de autoabastecerse de energ\u00eda, a trav\u00e9s de paneles fotovoltaicos, refrigeraci\u00f3n pasiva, calentadores solares de agua y estufas a le\u00f1a.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/casaaaa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12648\" title=\"Otro ejemplo de casa hecha a partir de containers reciclados\" src=\"http:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/casaaaa.jpg\" alt=\"\" width=\"538\" height=\"396\" \/><\/a><\/p>\n<p><span style=\"color: #888888;\"><span style=\"font-size: medium;\"><strong>Redondo Beach Container House<\/strong><\/span><\/span><\/p>\n<a href=\"http:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/redondo1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12649\" title=\"Casa Redondo Beach\" src=\"http:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/redondo1.jpg\" alt=\"\" width=\"537\" height=\"400\" \/><\/a>\n<p>En una de las playas m\u00e1s lujosas de California, podemos encontrar esta incre\u00edble casa hecha con 8 contenedores, directamente frente al mar. Es producto del estudio de arquitectura <a href=\"http:\/\/demariadesign.com\/2\/\" target=\"_blank\" rel=\"noopener\">De Maria Design,<\/a> que ofrece proyectos similares, adaptables a cada usuario.<\/p>\n<a href=\"http:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/Untitled-11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12650\" title=\"Distintas partes de la casa \" src=\"http:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/Untitled-11.jpg\" alt=\"\" width=\"718\" height=\"161\" \/><\/a>\n","protected":false},"excerpt":{"rendered":"<p>Las casas hechas con containers y otros elementos reciclados no son una novedad, pero s\u00ed lo es la creatividad y el dise\u00f1o que se est\u00e1n incorporando a este tipo de viviendas. Muchos las han denominado ya como \u201chabitainers\u201d. <\/p>\n","protected":false},"author":3,"featured_media":24444,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[2644,2646,2648,2650,2652,2654,2656,2658,2660,2662,2664],"class_list":["post-12646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundosostenible","tag-arquitectura-sostenible-es","tag-casas-modulares-es","tag-casas-recicladas-es","tag-ciudad-container-de-londres-es","tag-contenedores-es","tag-creatividad-es","tag-de-maria-design-es","tag-diseno-es","tag-eco-tech-design-es","tag-infiniski-es","tag-luis-de-garrido-es"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Las casas hechas con containers no son una novedad pero s\u00ed lo es la creatividad y el dise\u00f1o que se est\u00e1n incorporando a este tipo de viviendas.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"ecoblog\"\/>\n\t<meta name=\"keywords\" content=\"arquitectura sostenible,casas modulares,ciudad container de londres,contenedores,de maria design,eco tech design,infiniski,luis de garrido,casas recicladas,creatividad,dise\u00f1o\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"ecoblog mcp | Ecoblog de la MCP\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Casas modulares fabricadas con contenedores: baratas y ecol\u00f3gicas | ecoblog mcp\" \/>\n\t\t<meta property=\"og:description\" content=\"Las casas hechas con containers no son una novedad pero s\u00ed lo es la creatividad y el dise\u00f1o que se est\u00e1n incorporando a este tipo de viviendas.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-05-23T12:47:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-07-04T11:29:47+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Casas modulares fabricadas con contenedores: baratas y ecol\u00f3gicas | ecoblog mcp\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Las casas hechas con containers no son una novedad pero s\u00ed lo es la creatividad y el dise\u00f1o que se est\u00e1n incorporando a este tipo de viviendas.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\\\/#article\",\"name\":\"Casas modulares fabricadas con contenedores: baratas y ecol\\u00f3gicas | ecoblog mcp\",\"headline\":\"Casas modulares fabricadas con contenedores: baratas y ecol\\u00f3gicas\",\"author\":{\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/author\\\/ecoblog\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/containers.bmp\",\"width\":715,\"height\":449},\"datePublished\":\"2012-05-23T14:47:41+02:00\",\"dateModified\":\"2017-07-04T13:29:47+02:00\",\"inLanguage\":\"es-ES\",\"commentCount\":8,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\\\/#webpage\"},\"articleSection\":\"Mundo sostenible, arquitectura sostenible, Casas modulares, casas recicladas, Ciudad container de Londres, contenedores, creatividad, De Maria Design, dise\\u00f1o, Eco tech design, Infiniski, Luis de Garrido, Espa\\u00f1ol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/category\\\/mundosostenible\\\/#listItem\",\"name\":\"Mundo sostenible\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/category\\\/mundosostenible\\\/#listItem\",\"position\":2,\"name\":\"Mundo sostenible\",\"item\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/category\\\/mundosostenible\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\\\/#listItem\",\"name\":\"Casas modulares fabricadas con contenedores: baratas y ecol\\u00f3gicas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\\\/#listItem\",\"position\":3,\"name\":\"Casas modulares fabricadas con contenedores: baratas y ecol\\u00f3gicas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/category\\\/mundosostenible\\\/#listItem\",\"name\":\"Mundo sostenible\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/#organization\",\"name\":\"Mancomunidad de la Comarca de Pamplona\",\"description\":\"Ecoblog de la MCP\",\"url\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/author\\\/ecoblog\\\/#author\",\"url\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/author\\\/ecoblog\\\/\",\"name\":\"ecoblog\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/756e6c78901d3d59d5422af2a914e2892223a1aa3361eb209180b9039121115e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"ecoblog\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\\\/#webpage\",\"url\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\\\/\",\"name\":\"Casas modulares fabricadas con contenedores: baratas y ecol\\u00f3gicas | ecoblog mcp\",\"description\":\"Las casas hechas con containers no son una novedad pero s\\u00ed lo es la creatividad y el dise\\u00f1o que se est\\u00e1n incorporando a este tipo de viviendas.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/author\\\/ecoblog\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/author\\\/ecoblog\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/containers.bmp\",\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\\\/#mainImage\",\"width\":715,\"height\":449},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\\\/#mainImage\"},\"datePublished\":\"2012-05-23T14:47:41+02:00\",\"dateModified\":\"2017-07-04T13:29:47+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/#website\",\"url\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/\",\"name\":\"ecoblog mcp\",\"alternateName\":\"ecoblog mcp\",\"description\":\"Ecoblog de la MCP\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ecoblog.mcp.es\\\/l4r\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Casas modulares fabricadas con contenedores: baratas y ecol\u00f3gicas | ecoblog mcp","description":"Las casas hechas con containers no son una novedad pero s\u00ed lo es la creatividad y el dise\u00f1o que se est\u00e1n incorporando a este tipo de viviendas.","canonical_url":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/","robots":"max-image-preview:large","keywords":"arquitectura sostenible,casas modulares,ciudad container de londres,contenedores,de maria design,eco tech design,infiniski,luis de garrido,casas recicladas,creatividad,dise\u00f1o","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/#article","name":"Casas modulares fabricadas con contenedores: baratas y ecol\u00f3gicas | ecoblog mcp","headline":"Casas modulares fabricadas con contenedores: baratas y ecol\u00f3gicas","author":{"@id":"https:\/\/ecoblog.mcp.es\/l4r\/author\/ecoblog\/#author"},"publisher":{"@id":"https:\/\/ecoblog.mcp.es\/l4r\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/containers.bmp","width":715,"height":449},"datePublished":"2012-05-23T14:47:41+02:00","dateModified":"2017-07-04T13:29:47+02:00","inLanguage":"es-ES","commentCount":8,"mainEntityOfPage":{"@id":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/#webpage"},"isPartOf":{"@id":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/#webpage"},"articleSection":"Mundo sostenible, arquitectura sostenible, Casas modulares, casas recicladas, Ciudad container de Londres, contenedores, creatividad, De Maria Design, dise\u00f1o, Eco tech design, Infiniski, Luis de Garrido, Espa\u00f1ol"},{"@type":"BreadcrumbList","@id":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ecoblog.mcp.es\/l4r#listItem","position":1,"name":"Inicio","item":"https:\/\/ecoblog.mcp.es\/l4r","nextItem":{"@type":"ListItem","@id":"https:\/\/ecoblog.mcp.es\/l4r\/category\/mundosostenible\/#listItem","name":"Mundo sostenible"}},{"@type":"ListItem","@id":"https:\/\/ecoblog.mcp.es\/l4r\/category\/mundosostenible\/#listItem","position":2,"name":"Mundo sostenible","item":"https:\/\/ecoblog.mcp.es\/l4r\/category\/mundosostenible\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/#listItem","name":"Casas modulares fabricadas con contenedores: baratas y ecol\u00f3gicas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ecoblog.mcp.es\/l4r#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/#listItem","position":3,"name":"Casas modulares fabricadas con contenedores: baratas y ecol\u00f3gicas","previousItem":{"@type":"ListItem","@id":"https:\/\/ecoblog.mcp.es\/l4r\/category\/mundosostenible\/#listItem","name":"Mundo sostenible"}}]},{"@type":"Organization","@id":"https:\/\/ecoblog.mcp.es\/l4r\/#organization","name":"Mancomunidad de la Comarca de Pamplona","description":"Ecoblog de la MCP","url":"https:\/\/ecoblog.mcp.es\/l4r\/"},{"@type":"Person","@id":"https:\/\/ecoblog.mcp.es\/l4r\/author\/ecoblog\/#author","url":"https:\/\/ecoblog.mcp.es\/l4r\/author\/ecoblog\/","name":"ecoblog","image":{"@type":"ImageObject","@id":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/756e6c78901d3d59d5422af2a914e2892223a1aa3361eb209180b9039121115e?s=96&d=mm&r=g","width":96,"height":96,"caption":"ecoblog"}},{"@type":"WebPage","@id":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/#webpage","url":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/","name":"Casas modulares fabricadas con contenedores: baratas y ecol\u00f3gicas | ecoblog mcp","description":"Las casas hechas con containers no son una novedad pero s\u00ed lo es la creatividad y el dise\u00f1o que se est\u00e1n incorporando a este tipo de viviendas.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ecoblog.mcp.es\/l4r\/#website"},"breadcrumb":{"@id":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/#breadcrumblist"},"author":{"@id":"https:\/\/ecoblog.mcp.es\/l4r\/author\/ecoblog\/#author"},"creator":{"@id":"https:\/\/ecoblog.mcp.es\/l4r\/author\/ecoblog\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ecoblog.mcp.es\/l4r\/wp-content\/uploads\/2012\/05\/containers.bmp","@id":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/#mainImage","width":715,"height":449},"primaryImageOfPage":{"@id":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/#mainImage"},"datePublished":"2012-05-23T14:47:41+02:00","dateModified":"2017-07-04T13:29:47+02:00"},{"@type":"WebSite","@id":"https:\/\/ecoblog.mcp.es\/l4r\/#website","url":"https:\/\/ecoblog.mcp.es\/l4r\/","name":"ecoblog mcp","alternateName":"ecoblog mcp","description":"Ecoblog de la MCP","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ecoblog.mcp.es\/l4r\/#organization"}}]},"og:locale":"es_ES","og:site_name":"ecoblog mcp | Ecoblog de la MCP","og:type":"article","og:title":"Casas modulares fabricadas con contenedores: baratas y ecol\u00f3gicas | ecoblog mcp","og:description":"Las casas hechas con containers no son una novedad pero s\u00ed lo es la creatividad y el dise\u00f1o que se est\u00e1n incorporando a este tipo de viviendas.","og:url":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/","article:published_time":"2012-05-23T12:47:41+00:00","article:modified_time":"2017-07-04T11:29:47+00:00","twitter:card":"summary","twitter:title":"Casas modulares fabricadas con contenedores: baratas y ecol\u00f3gicas | ecoblog mcp","twitter:description":"Las casas hechas con containers no son una novedad pero s\u00ed lo es la creatividad y el dise\u00f1o que se est\u00e1n incorporando a este tipo de viviendas."},"aioseo_meta_data":{"post_id":"12646","title":"Casas modulares fabricadas con contenedores: baratas y ecol\u00f3gicas | #site_title","description":"Las casas hechas con containers no son una novedad pero s\u00ed lo es la creatividad y el dise\u00f1o que se est\u00e1n incorporando a este tipo de viviendas.","keywords":[{"label":"arquitectura sostenible","value":"arquitectura sostenible"},{"label":"Casas modulares","value":"Casas modulares"},{"label":"Ciudad container de Londres","value":"Ciudad container de Londres"},{"label":"contenedores","value":"contenedores"},{"label":"De Maria Design","value":"De Maria Design"},{"label":"Eco tech design","value":"Eco tech design"},{"label":"Infiniski","value":"Infiniski"},{"label":"Luis de Garrido","value":"Luis de Garrido"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-12-09 09:44:06","updated":"2025-06-05 04:37:05","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecoblog.mcp.es\/l4r\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecoblog.mcp.es\/l4r\/category\/mundosostenible\/\" title=\"Mundo sostenible\">Mundo sostenible<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCasas modulares fabricadas con contenedores: baratas y ecol\u00f3gicas\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/ecoblog.mcp.es\/l4r"},{"label":"Mundo sostenible","link":"https:\/\/ecoblog.mcp.es\/l4r\/category\/mundosostenible\/"},{"label":"Casas modulares fabricadas con contenedores: baratas y ecol\u00f3gicas","link":"https:\/\/ecoblog.mcp.es\/l4r\/casas-modulares-fabricadas-con-contenedores-baratas-y-ecologicas\/"}],"_links":{"self":[{"href":"https:\/\/ecoblog.mcp.es\/l4r\/wp-json\/wp\/v2\/posts\/12646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecoblog.mcp.es\/l4r\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecoblog.mcp.es\/l4r\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecoblog.mcp.es\/l4r\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ecoblog.mcp.es\/l4r\/wp-json\/wp\/v2\/comments?post=12646"}],"version-history":[{"count":3,"href":"https:\/\/ecoblog.mcp.es\/l4r\/wp-json\/wp\/v2\/posts\/12646\/revisions"}],"predecessor-version":[{"id":24446,"href":"https:\/\/ecoblog.mcp.es\/l4r\/wp-json\/wp\/v2\/posts\/12646\/revisions\/24446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecoblog.mcp.es\/l4r\/wp-json\/wp\/v2\/media\/24444"}],"wp:attachment":[{"href":"https:\/\/ecoblog.mcp.es\/l4r\/wp-json\/wp\/v2\/media?parent=12646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecoblog.mcp.es\/l4r\/wp-json\/wp\/v2\/categories?post=12646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecoblog.mcp.es\/l4r\/wp-json\/wp\/v2\/tags?post=12646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}